{"id":225,"date":"2019-10-15T15:59:34","date_gmt":"2019-10-15T13:59:34","guid":{"rendered":"https:\/\/eventiyoga.it\/blog\/?p=225"},"modified":"2021-08-24T11:24:02","modified_gmt":"2021-08-24T09:24:02","slug":"perche-iniziare-a-fare-yoga","status":"publish","type":"post","link":"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/","title":{"rendered":"Perch\u00e9 iniziare a fare yoga"},"content":{"rendered":"\n<p>Lo yoga \u00e8 una <a href=\"https:\/\/en.wikipedia.org\/wiki\/Yoga\" target=\"_blank\" rel=\"noopener noreferrer\">disciplina<\/a> davvero antichissima nata in India migliaia di anni fa allo scopo di migliorare la vita dei praticanti sia a livello fisico che, soprattutto, spirituale.<\/p>\n\n\n\n<p>Non a caso la parola \u201c<em>yoga<\/em>\u201d significa \u201c<em>unione<\/em>\u201d e, nonostante molte persone oggi pensano che si tratti di una vera e propria attivit\u00e0 fisica per rimettersi in forma che ti permette di accavallare le gambe dietro la testa, in realt\u00e0 lo <strong>yoga<\/strong> resta una disciplina fortemente spirituale. Ma, soprattutto, una <strong>disciplina che tutti possono praticare<\/strong> senza distinzioni di forma fisica, et\u00e0 e ovviamente sesso.<\/p>\n\n\n\n<p>Sono tanti i motivi per cui \u00e8 bene iniziare a fare yoga, basti solo pensare che spesso questa disciplina \u00e8 utilizzata anche per <a href=\"https:\/\/eventiyoga.it\/blog\/yoga-contro-la-depressione\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (apre in una nuova scheda)\">combattere la depressione<\/a> (unita ad altre misure, se necessario).<\/p>\n\n\n\n<p>Nel corso degli ultimi anni, inoltre, sono stati effettuati molti studi clinici in diversi Paesi e tutti hanno rilevato che lo yoga ha un impatto positivo sulla salute.&nbsp;<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_68_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#Perche_iniziare_a_fare_yoga\" title=\"Perch\u00e9 iniziare a fare yoga?\">Perch\u00e9 iniziare a fare yoga?<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#Scopri_tutti_i_motivi_per_cui_iniziare_la_tua_pratica\" title=\"Scopri tutti i motivi per cui iniziare la tua pratica:\">Scopri tutti i motivi per cui iniziare la tua pratica:<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#Tre_risorse_interessanti_per_te\" title=\"Tre risorse interessanti per te\">Tre risorse interessanti per te<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#Scarica_la_nuova_APP_di_Eventiyoga\" title=\"Scarica la nuova APP di Eventiyoga\">Scarica la nuova APP di Eventiyoga<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#Calendario_Eventi_Yoga_online\" title=\"Calendario Eventi Yoga online\">Calendario Eventi Yoga online<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#Iscriviti_alla_Newsletter\" title=\"Iscriviti alla Newsletter\">Iscriviti alla Newsletter<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-perch-iniziare-a-fare-yoga\"><span class=\"ez-toc-section\" id=\"Perche_iniziare_a_fare_yoga\"><\/span>Perch\u00e9 iniziare a fare yoga?<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ecco i sei motivi per cui ciascuno di noi dovrebbe <a href=\"https:\/\/eventiyoga.it\/blog\/yoga-principianti\/\">iniziare a praticare yoga<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-1-un-ottima-attivit-fisica\">1. \u00c9 un\u2019ottima attivit\u00e0 fisica<\/h3>\n\n\n\n<p>Non nasce come attivit\u00e0 fisica ma, di fatto, lo yoga \u00e8 anche un\u2019attivit\u00e0 fisica che permette a tutti, senza esclusione, di mettere in moto il proprio corpo e di lavorare su tutte o solo su alcune parti di esso. Non \u00e8 necessario essere dei pro, basta seguire i movimenti che pi\u00f9 si adattano al nostro corpo per trarre beneficio dallo yoga. Infatti, le posizioni yoga possono essere adattate al proprio livello e anche alle proprie esigenze, cos\u00ec da costruire una pratica che sia benefica a livello fisico: ce ne sono per chi soffre di <a href=\"https:\/\/eventiyoga.it\/blog\/yoga-contro-mal-di-schiena-esercizi\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (apre in una nuova scheda)\">mal di schiena<\/a>, per chi ha <a rel=\"noreferrer noopener\" aria-label=\" (apre in una nuova scheda)\" href=\"https:\/\/eventiyoga.it\/blog\/le-migliori-posizioni-yoga-mal-testa\/\" target=\"_blank\">mal di testa<\/a>, per chi semplicemente vuole restare in forma. Insomma, c&#8217;\u00e8 un asana per tutti e per tutte le esigenze.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2018\/07\/terapia-yoga.jpg\" alt=\"\" class=\"wp-image-9265\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2018\/07\/terapia-yoga.jpg\" alt=\"\" class=\"wp-image-9265\"\/><\/noscript><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-2-aiuta-ad-utilizzare-il-respiro-nel-migliore-dei-modi-e-a-rilassarsi\">2. Aiuta ad utilizzare il respiro nel migliore dei modi e a rilassarsi<\/h3>\n\n\n\n<p>In base al <a href=\"https:\/\/eventiyoga.it\/blog\/come-scegliere-il-tipo-di-yoga-piu-adatto\/\">tipo di yoga<\/a> che decidi di praticare farai pi\u00f9 o meno esercizi di respirazione che ti permetteranno, fin da subito, di imparare a respirare in una maniera diversa, pi\u00f9 profonda e meno impulsiva. Imparare a respirare meglio significa far entrare maggior aria nel nostro corpo e, soprattutto, rilassarsi di pi\u00f9 e pi\u00f9 a lungo (se unito alla <a href=\"https:\/\/eventiyoga.it\/blog\/come-iniziare-a-fare-meditazione\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (apre in una nuova scheda)\">meditazione<\/a>, l&#8217;effetto dello yoga in questo senso \u00e8 ancora maggiore). Alcuni ricercatori della Boston University School of Medicine hanno studiato gli effetti di due settimane di yoga sui livelli neurotrasmettitori Gaga nel talamo e hanno messo a confronto questa pratica con camminate della stessa durata dimostrando che lo yoga migliora l&#8217;ansia e l&#8217;umore pi\u00f9 di una camminata in quanto agisce profondamente sul modo in cui respiriamo.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/10\/meditazione-regole.jpg\" alt=\"Meditazione senza dolori\" class=\"wp-image-2630\"\/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"849\" height=\"566\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/10\/meditazione-regole.jpg\" alt=\"Meditazione senza dolori\" class=\"wp-image-2630\" srcset=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/10\/meditazione-regole.jpg 849w, https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/10\/meditazione-regole-600x400.jpg 600w, https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/10\/meditazione-regole-300x200.jpg 300w, https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/10\/meditazione-regole-768x512.jpg 768w\" sizes=\"auto, (max-width: 849px) 100vw, 849px\" \/><\/noscript><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-3-aiuta-a-dormire-meglio\">3. Aiuta a dormire meglio<\/h3>\n\n\n\n<p>L\u2019attivit\u00e0 fisica in genere aiuta a dormire meglio ma lo yoga, e lo dico per esperienza personale, \u00e8 l\u2019attivit\u00e0 che pi\u00f9 aiuta in questo senso. Esistono delle posizioni pensate appositamente <a href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-rilassarsi\/\">per rilassare<\/a> e che dovrebbero essere praticate prima di andare a letto ma in generale lo yoga ti aiuta a riposare meglio perch\u00e9 mette in movimento tutti i muscoli del nostro corpo in una maniera che a noi sembra passiva ma che in realt\u00e0 \u00e8 solo pi\u00f9 dolce. La fatica potresti non sentirla durante la pratica ma il tuo corpo sicuramente la avvertir\u00e0 nel momento in cui prenderai sonno distendendosi e preparandosi ad una notte migliore. Scopri di pi\u00f9 sullo <a href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-dormire-posizioni-consigli\/\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (apre in una nuova scheda)\">yoga per dormire<\/a>.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2017\/07\/yoga-dormire-1024x682.jpg\" alt=\"yoga per dormire\" class=\"wp-image-6017\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2017\/07\/yoga-dormire-1024x682.jpg\" alt=\"yoga per dormire\" class=\"wp-image-6017\"\/><\/noscript><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-4-ideale-per-la-postura-l-equilibrio-e-la-flessibilit\">4. \u00c9 ideale per la postura,&nbsp;<strong>l&#8217;equilibrio e la flessibilit\u00e0<\/strong><\/h3>\n\n\n\n<p>Tra esercizi di allungamento, respirazione e stretching la postura grazie allo yoga migliora e, con essa, anche la schiena. Soprattutto se, come me, trascorri la maggior parte del tempo seduto la tua schiena ti ringrazier\u00e0 se inizierai a fare yoga e, soprattutto, non sarai costretto a fare esercizi faticosi o noiosi per trarre benefici dall\u2019attivit\u00e0 fisica.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2018\/10\/Yoga-Posturale-1024x768.jpg\" alt=\"Yoga posturale\" class=\"wp-image-10789\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2018\/10\/Yoga-Posturale-1024x768.jpg\" alt=\"Yoga posturale\" class=\"wp-image-10789\"\/><\/noscript><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-5-aumenta-la-concentrazione-e-la-resistenza-psicologica\">5. Aumenta la concentrazione e la resistenza psicologica<\/h3>\n\n\n\n<p>Praticare yoga, specie allo stadio avanzato, \u00e8 un esercizio di concentrazione sia perch\u00e9 devi ricordarti continuamente delle posizioni sia perch\u00e9, se ti distrai, perdi la connessione tra corpo e mente necessaria per portare a termine le sequenze. Facendo ci\u00f2, la pratica ti mette continuamente in discussione e aumenta la tua capacit\u00e0 di concentrarti e pensare solo a ci\u00f2 che stai facendo nel momento in cui lo stai facendo. Il risultato? Una pi\u00f9 alta capacit\u00e0 di concentrazione anche nella vita quotidiana e la possibilit\u00e0 di restare focalizzato sul momento che vivi e sull\u2019attivit\u00e0 che stai facendo nel momento in cui la stai facendo. Scopri di pi\u00f9 sui <a href=\"https:\/\/eventiyoga.it\/blog\/benefici-psicologici-yoga\/\">benefici psicologici dello yoga<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2017\/03\/benefici-psicologici-yoga-.jpg\" alt=\"benefici psicologici yoga\" class=\"wp-image-4738\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2017\/03\/benefici-psicologici-yoga-.jpg\" alt=\"benefici psicologici yoga\" class=\"wp-image-4738\"\/><\/noscript><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-6-aiuta-a-seguire-uno-stile-di-vita-pi-sano\">6. Aiuta a seguire uno stile di vita pi\u00f9 sano<\/h3>\n\n\n\n<p>Stando alle statistiche e alle ricerche, quelli che praticano yoga tendono a seguire uno stile di vita pi\u00f9 sano, ad alimentarsi meglio e a seguire i ritmi della natura. Ci\u00f2 garantisce una qualit\u00e0 della vita migliore e pi\u00f9 attenta. Ci\u00f2 non vuol dire diventare vegani o vegetariani, sia chiaro, ma semplicemente prestare pi\u00f9 attenzione al proprio corpo per nutrire corpo e anima.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/08\/dieta-vegana-1024x705.jpg\" alt=\"dieta vegana\" class=\"wp-image-2047\"\/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"705\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/08\/dieta-vegana-1024x705.jpg\" alt=\"dieta vegana\" class=\"wp-image-2047\" srcset=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/08\/dieta-vegana-1024x705.jpg 1024w, https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/08\/dieta-vegana-600x413.jpg 600w, https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/08\/dieta-vegana-300x206.jpg 300w, https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/08\/dieta-vegana-768x529.jpg 768w, https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/08\/dieta-vegana.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure><\/div>\n\n\n\n<p>Questo sono solo sei dei motivi per cui provare lo yoga ma ce ne sono molti altri, e dipendono dalla propria personalit\u00e0 e dai propri bisogni.<\/p>\n\n\n\n<p>Del resto, come diceva&nbsp;B.K.S. Iyengar:<\/p>\n\n\n\n<p><em><strong>Lo yoga non cambia solo il modo di guardare le cose, ma trasforma anche la persona che le guarda.<\/strong><\/em><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-scopri-tutti-i-motivi-per-cui-iniziare-la-tua-pratica\"><span class=\"ez-toc-section\" id=\"Scopri_tutti_i_motivi_per_cui_iniziare_la_tua_pratica\"><\/span>Scopri tutti i motivi per cui iniziare la tua pratica:<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure><iframe data-src=\"https:\/\/www.youtube.com\/embed\/KcDgS6Tr-dw?rel=0\" width=\"1280\" height=\"720\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><noscript><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/KcDgS6Tr-dw?rel=0\" width=\"1280\" height=\"720\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/noscript><\/figure>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-block-buttons-is-layout-flex\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-tre-risorse-interessanti-per-te\"><span class=\"ez-toc-section\" id=\"Tre_risorse_interessanti_per_te\"><\/span>Tre risorse interessanti per te<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><a href=\"https:\/\/eventiyoga.it\/blog\/libri-yoga-da-leggere-assolutamente\/\" class=\"ek-link\"><strong>Libri yoga da leggere assolutamente: 11 titoli imperdibili<\/strong><\/a><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/eventiyoga.it\/blog\/libri-sulla-meditazione\/\" class=\"ek-link\">Libri sulla meditazione: i migliori per imparare<\/a><\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/eventiyoga.it\/blog\/lezioni-yoga-online-gratis-youtube\/\" class=\"ek-link\">Le migliori lezioni gratis di yoga online su Youtube<\/a><\/strong><\/p>\n\n\n\n<p><a href=\"https:\/\/eventiyoga.it\/blog\/namaste-significato-saluto-indiano\/\" class=\"ek-link\"><strong>Namast\u00e9, il significato del saluto indiano<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-scarica-la-nuova-app-di-eventiyoga\"><span class=\"ez-toc-section\" id=\"Scarica_la_nuova_APP_di_Eventiyoga\"><\/span>Scarica la nuova APP di Eventiyoga<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ogni mese scegli tra centinaia di vacanze, retreat, viaggi e corsi di yoga per tutti i gusti.<\/p>\n\n\n\n<p>Cerca l\u2019evento che pi\u00f9 ti piace direttamente dalla App, chiedi informazioni, e&nbsp;<strong>prenota con un click<\/strong>!<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/eventiyoga.it\/blog\/app-eventiyoga\/\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/09\/scarica_app_eventiyoga-1024x1024.jpg\" alt=\"vacanze in Italia yoga sull'app Eventiyoga \" class=\"wp-image-23361\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/09\/scarica_app_eventiyoga-1024x1024.jpg\" alt=\"vacanze in Italia yoga sull'app Eventiyoga \" class=\"wp-image-23361\"\/><\/noscript><\/a><figcaption>Scarica l\u2019APP di Eventi Yoga. E&#8217; gratuito.<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/apps.apple.com\/us\/app\/id1514783292\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\"><strong>APP EVENTI YOGA per iOS<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.maugry.yoga\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>APP EVENTI YOGA per Android<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-calendario-eventi-yoga-online\"><span class=\"ez-toc-section\" id=\"Calendario_Eventi_Yoga_online\"><\/span>Calendario Eventi Yoga online<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Puoi consultare il calendario eventi anche online con numerosi weekend, vacanze, ritiri e corsi yoga.<\/p>\n\n\n\n<p>Cerca qui gli eventi yoga di tuo interesse divisi per mese e regione.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-workshop-yoga-e-benessere-gennaio\/\">Gennaio<\/a><\/strong><\/li><li><strong><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-seminari-workshop-yoga-benessere-febbraio\/\">Febbraio<\/a><\/strong><\/li><li><strong><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-seminari-workshop-yoga-benessere-marzo\/\">Marzo<\/a><\/strong><\/li><li><strong><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-aprile\/\">Aprile<\/a><\/strong><\/li><li><strong><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-maggio\/\">Maggio<\/a><\/strong><\/li><li><strong><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-e-benessere-giugno-offerte\/\">Giugno<\/a><\/strong><\/li><li><strong><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-e-benessere-luglio-offerte\/\">Luglio<\/a><\/strong><\/li><li><strong><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-e-benessere-agosto-offerte\/\">Agosto<\/a><\/strong><\/li><li><strong><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-e-benessere-settembre-offerte\/\">Settembre<\/a><\/strong><\/li><li><strong><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-e-benessere-ottobre-offerte\/\">Ottobre<\/a><\/strong><\/li><li><strong><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-e-benessere-novembre-offerte\/\">Novembre<\/a><\/strong><\/li><li><strong><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-e-benessere-dicembre\/\">Dicembre<\/a><\/strong><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-iscriviti-alla-newsletter\"><span class=\"ez-toc-section\" id=\"Iscriviti_alla_Newsletter\"><\/span>Iscriviti alla Newsletter<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image size-large caption-align-center\"><a href=\"https:\/\/eventiyoga.it\/blog\/newsletter-eventi-yoga\/\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/10\/Banner-Iscrizione-NL.jpg\" alt=\"Iscriviti alla Newsletter \u2013 Per te subito un Bonus!\" class=\"wp-image-16731\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/10\/Banner-Iscrizione-NL.jpg\" alt=\"Iscriviti alla Newsletter \u2013 Per te subito un Bonus!\" class=\"wp-image-16731\"\/><\/noscript><\/a><figcaption>Iscriviti alla Newsletter \u2013 Per te subito un Bonus!<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Lo yoga \u00e8 una disciplina davvero antichissima nata in India migliaia di anni fa allo scopo di migliorare la vita dei praticanti sia a livello fisico che, soprattutto, spirituale. Non a caso la parola \u201cyoga\u201d significa \u201cunione\u201d e, nonostante molte persone oggi pensano che si tratti di una vera e propria attivit\u00e0 fisica per rimettersi [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":15387,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":5,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[41],"tags":[38],"class_list":["post-225","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tips","tag-praticare-yoga"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Perch\u00e9 iniziare a fare yoga? ECCOTI I 6 BUONI MOTIVI!<\/title>\n<meta name=\"description\" content=\"Perch\u00e9 iniziare a fare yoga? Scopri con noi 6 motivi per cui vale davvero la pena iniziare a praticare yoga. Clicca subito qui!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Perch\u00e9 iniziare a fare yoga? ECCOTI I 6 BUONI MOTIVI!\" \/>\n<meta property=\"og:description\" content=\"Perch\u00e9 iniziare a fare yoga? Scopri con noi 6 motivi per cui vale davvero la pena iniziare a praticare yoga. Clicca subito qui!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/\" \/>\n<meta property=\"og:site_name\" content=\"Eventi Yoga\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-15T13:59:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-24T09:24:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/04\/Perche-iniziare-fare-yoga.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Elena Petrunina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elena Petrunina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/\",\"url\":\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/\",\"name\":\"Perch\u00e9 iniziare a fare yoga? ECCOTI I 6 BUONI MOTIVI!\",\"isPartOf\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/04\/Perche-iniziare-fare-yoga.png\",\"datePublished\":\"2019-10-15T13:59:34+00:00\",\"dateModified\":\"2021-08-24T09:24:02+00:00\",\"author\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/#\/schema\/person\/ff7e282f858c6f25b96e84f395450004\"},\"description\":\"Perch\u00e9 iniziare a fare yoga? Scopri con noi 6 motivi per cui vale davvero la pena iniziare a praticare yoga. Clicca subito qui!\",\"breadcrumb\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#primaryimage\",\"url\":\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/04\/Perche-iniziare-fare-yoga.png\",\"contentUrl\":\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/04\/Perche-iniziare-fare-yoga.png\",\"width\":1080,\"height\":810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eventiyoga.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Perch\u00e9 iniziare a fare yoga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/#website\",\"url\":\"https:\/\/eventiyoga.it\/blog\/\",\"name\":\"Eventi Yoga\",\"description\":\"Il portale Italiano per gli eventi dello yoga\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eventiyoga.it\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/#\/schema\/person\/ff7e282f858c6f25b96e84f395450004\",\"name\":\"Elena Petrunina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8760e76687c89b2c8f079a98b908a440b7152ebe9b0fc336b996432343253efe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8760e76687c89b2c8f079a98b908a440b7152ebe9b0fc336b996432343253efe?s=96&d=mm&r=g\",\"caption\":\"Elena Petrunina\"},\"description\":\"Yoga Marketing Coach &amp; Fondatrice di EventiYoga.it, il portale che ha connesso migliaia di insegnanti con oltre 1 milione di praticanti yoga in Italia. Aiuto insegnanti yoga a definire la loro unicit\u00e0, farsi trovare dalle persone giuste e creare programmi e ritiri yoga trasformativi e altamente richiesti.\",\"url\":\"https:\/\/eventiyoga.it\/blog\/author\/elena-petrunina\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Perch\u00e9 iniziare a fare yoga? ECCOTI I 6 BUONI MOTIVI!","description":"Perch\u00e9 iniziare a fare yoga? Scopri con noi 6 motivi per cui vale davvero la pena iniziare a praticare yoga. Clicca subito qui!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/","og_locale":"en_US","og_type":"article","og_title":"Perch\u00e9 iniziare a fare yoga? ECCOTI I 6 BUONI MOTIVI!","og_description":"Perch\u00e9 iniziare a fare yoga? Scopri con noi 6 motivi per cui vale davvero la pena iniziare a praticare yoga. Clicca subito qui!","og_url":"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/","og_site_name":"Eventi Yoga","article_published_time":"2019-10-15T13:59:34+00:00","article_modified_time":"2021-08-24T09:24:02+00:00","og_image":[{"width":1080,"height":810,"url":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/04\/Perche-iniziare-fare-yoga.png","type":"image\/png"}],"author":"Elena Petrunina","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Elena Petrunina","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/","url":"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/","name":"Perch\u00e9 iniziare a fare yoga? ECCOTI I 6 BUONI MOTIVI!","isPartOf":{"@id":"https:\/\/eventiyoga.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#primaryimage"},"image":{"@id":"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#primaryimage"},"thumbnailUrl":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/04\/Perche-iniziare-fare-yoga.png","datePublished":"2019-10-15T13:59:34+00:00","dateModified":"2021-08-24T09:24:02+00:00","author":{"@id":"https:\/\/eventiyoga.it\/blog\/#\/schema\/person\/ff7e282f858c6f25b96e84f395450004"},"description":"Perch\u00e9 iniziare a fare yoga? Scopri con noi 6 motivi per cui vale davvero la pena iniziare a praticare yoga. Clicca subito qui!","breadcrumb":{"@id":"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#primaryimage","url":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/04\/Perche-iniziare-fare-yoga.png","contentUrl":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/04\/Perche-iniziare-fare-yoga.png","width":1080,"height":810},{"@type":"BreadcrumbList","@id":"https:\/\/eventiyoga.it\/blog\/perche-iniziare-a-fare-yoga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eventiyoga.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Perch\u00e9 iniziare a fare yoga"}]},{"@type":"WebSite","@id":"https:\/\/eventiyoga.it\/blog\/#website","url":"https:\/\/eventiyoga.it\/blog\/","name":"Eventi Yoga","description":"Il portale Italiano per gli eventi dello yoga","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eventiyoga.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/eventiyoga.it\/blog\/#\/schema\/person\/ff7e282f858c6f25b96e84f395450004","name":"Elena Petrunina","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eventiyoga.it\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8760e76687c89b2c8f079a98b908a440b7152ebe9b0fc336b996432343253efe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8760e76687c89b2c8f079a98b908a440b7152ebe9b0fc336b996432343253efe?s=96&d=mm&r=g","caption":"Elena Petrunina"},"description":"Yoga Marketing Coach &amp; Fondatrice di EventiYoga.it, il portale che ha connesso migliaia di insegnanti con oltre 1 milione di praticanti yoga in Italia. Aiuto insegnanti yoga a definire la loro unicit\u00e0, farsi trovare dalle persone giuste e creare programmi e ritiri yoga trasformativi e altamente richiesti.","url":"https:\/\/eventiyoga.it\/blog\/author\/elena-petrunina\/"}]}},"_links":{"self":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/posts\/225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/comments?post=225"}],"version-history":[{"count":0,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/posts\/225\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/media\/15387"}],"wp:attachment":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/media?parent=225"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/categories?post=225"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/tags?post=225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}