{"id":39948,"date":"2018-02-16T14:36:00","date_gmt":"2018-02-16T13:36:00","guid":{"rendered":"https:\/\/eventiyoga.it\/blog\/?p=39948"},"modified":"2022-02-22T14:45:25","modified_gmt":"2022-02-22T13:45:25","slug":"vacanze-olistiche-2018","status":"publish","type":"post","link":"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/","title":{"rendered":"Vacanze Olistiche 2018: destinazioni in Italia"},"content":{"rendered":"\n<p>Sei alla ricerca di una destinazione per una vacanza all&#8217;insegna dello yoga? O forse non sei sicuro da dove iniziare e hai bisogno di qualche consiglio. In entrambi i casi, questo post del blog \u00e8 per te! Abbiamo raccolto alcune delle nostre destinazioni preferite incentrate sullo yoga e abbiamo incluso alcuni consigli per aiutarti a rendere la tua vacanza il pi\u00f9 rilassante e rigenerante possibile. Buon viaggio!<\/p>\n\n\n<div class=\"yoga-events-empty\"><p>Non ci sono eventi yoga in questo periodo.<\/p><\/div>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_68_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#Scarica_lApp_Eventi_Yoga\" title=\"Scarica l\u2019App Eventi Yoga\">Scarica l\u2019App Eventi Yoga<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#Archivio_vacanze_olistiche\" title=\"Archivio vacanze olistiche\">Archivio vacanze olistiche<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#Calendario_Eventi_Yoga_online\" title=\"Calendario Eventi Yoga online\">Calendario Eventi Yoga online<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#Iscriviti_alla_nostra_Newsletter\" title=\"Iscriviti alla nostra Newsletter\">Iscriviti alla nostra Newsletter<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Scarica_lApp_Eventi_Yoga\"><\/span>Scarica l\u2019App Eventi Yoga<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Il pi\u00f9 grande catalogo degli eventi di <a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-italia-consigli\/\">yoga in Italia<\/a> di Eventiyoga.it sempre a portata di mano! Centinaia di vacanze, retreat, viaggi e corsi di yoga per tutti i gusti da scegliere con un click.<\/p>\n\n\n\n<p class=\"has-text-align-center\" id=\"block-96d89c7f-cecf-4b0a-8461-7912ee307496\"><strong><em>Scarica ora l\u2019app&nbsp;<\/em>EventiYoga<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image caption-align-center\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/09\/scarica_app_eventiyoga-1.jpg\" alt=\"Scarica App EventiYoga\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/09\/scarica_app_eventiyoga-1.jpg\" alt=\"Scarica App EventiYoga\"\/><\/noscript><figcaption>Scarica l\u2019App di Eventi Yoga<\/figcaption><\/figure>\n\n\n\n<p class=\"has-text-align-center\" id=\"block-68cf4cf1-ec23-4bba-beb8-532006304b3c\"><a href=\"https:\/\/apps.apple.com\/us\/app\/id1514783292\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>App E<\/strong><\/a><strong><a href=\"https:\/\/apps.apple.com\/us\/app\/id1514783292\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">v<\/a><\/strong><a href=\"https:\/\/apps.apple.com\/us\/app\/id1514783292\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\"><strong>enti Yoga per iOS<\/strong><\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\" id=\"block-cdf6bb43-5eae-4253-970a-48fb0b59e54a\"><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.maugry.yoga\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>App Eventi Yoga per Android<\/strong><\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Archivio_vacanze_olistiche\"><\/span>Archivio vacanze olistiche<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Qui trovi tutte le vacanze degli anni passati all\u2019insegna dello Yoga, Ayurveda, Detox, Meditazione e Risveglio dell\u2019anima.<\/p>\n\n\n\n<p><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche\/\" class=\"ek-link\">Vacanze Olistiche 2022<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2021-migliori-destinazioni\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vacanze Olistiche 2021<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2020\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vacanze Olistiche 2020<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2019\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vacanze Olistiche 2019<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/\" target=\"_blank\" rel=\"noreferrer noopener\">Vacanze Olistiche 2018<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"block-807ae674-37db-4617-81e4-a649d9041dac\"><span class=\"ez-toc-section\" id=\"Calendario_Eventi_Yoga_online\"><\/span>Calendario Eventi Yoga online<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p id=\"block-bc0f03ce-aa47-4c55-bd8a-b86172e6fadf\">Puoi consultare il calendario eventi anche online con numerosi weekend, vacanze, ritiri e corsi yoga.<\/p>\n\n\n\n<p id=\"block-d91f1143-42f6-4f1e-94b1-369745ca1955\">Cerca qui gli eventi yoga di tuo interesse divisi per mese e regione.<\/p>\n\n\n\n<ul class=\"wp-block-list\" id=\"block-e452dcf4-2a63-4aea-a71d-f2860d711241\"><li><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-workshop-yoga-e-benessere-gennaio\/\"><strong>Gennaio<\/strong><\/a><\/li><li><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-workshop-yoga-e-benessere-gennaio\/\"><strong>Febbraio<\/strong><\/a><\/li><li><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-seminari-workshop-yoga-benessere-marzo\/\"><strong>Marzo<\/strong><\/a><\/li><li><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-seminari-workshop-yoga-benessere-marzo\/\"><strong>Aprile<\/strong><\/a><\/li><li><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-seminari-workshop-yoga-benessere-marzo\/\"><strong>Maggio<\/strong><\/a><\/li><li><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-seminari-workshop-yoga-benessere-marzo\/\"><strong>Giugno<\/strong><\/a><\/li><li><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-seminari-workshop-yoga-benessere-marzo\/\"><strong>Luglio<\/strong><\/a><\/li><li><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-e-benessere-luglio-offerte\/\"><strong>Agosto<\/strong><\/a><\/li><li><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-e-benessere-luglio-offerte\/\"><strong>Settembre<\/strong><\/a><\/li><li><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-e-benessere-luglio-offerte\/\"><strong>Ottobre<\/strong><\/a><\/li><li><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-e-benessere-luglio-offerte\/\"><strong>Novembre<\/strong><\/a><\/li><li><a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-e-benessere-luglio-offerte\/\"><strong>Dicembre<\/strong><\/a><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"block-ed11dde2-5ec0-4f9c-900e-872eb5d8960b\"><span class=\"ez-toc-section\" id=\"Iscriviti_alla_nostra_Newsletter\"><\/span>Iscriviti alla nostra Newsletter<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Resta sempre aggiornato sulle iniziative yoga in Italia. Inviamo ogni settimana solo notizie rilevanti per te!<\/p>\n\n\n\n<figure class=\"wp-block-image caption-align-center\" id=\"block-5a3896ef-7acb-4a6a-b879-20e7ed06b13b\"><a href=\"https:\/\/pinterest.com\/pin\/create\/bookmarklet\/?is_video=false&amp;url=https%3A%2F%2Feventiyoga.it%2Fyoga-vicino-a-me%2F&amp;media=https%3A%2F%2Feventiyoga.it%2Fwp-content%2Fuploads%2F2019%2F10%2FBanner-Iscrizione-NL-EY.jpeg&amp;description=Questa%20immagine%20ha%20l%27attributo%20alt%20vuoto%3B%20il%20nome%20del%20file%20%C3%A8%20Banner-Iscrizione-NL-EY.jpeg\" target=\"_blank\" rel=\"noreferrer noopener\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/10\/Banner-Iscrizione-NL-EY.jpeg\" alt=\"Questa immagine ha l'attributo alt vuoto; il nome del file \u00e8 Banner-Iscrizione-NL-EY.jpeg\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/10\/Banner-Iscrizione-NL-EY.jpeg\" alt=\"Questa immagine ha l'attributo alt vuoto; il nome del file \u00e8 Banner-Iscrizione-NL-EY.jpeg\"\/><\/noscript><\/a><figcaption>Iscriviti alla Newsletter \u2013 per te subito un Bonus!<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Sei alla ricerca di una destinazione per una vacanza all&#8217;insegna dello yoga? O forse non sei sicuro da dove iniziare e hai bisogno di qualche consiglio. In entrambi i casi, questo post del blog \u00e8 per te! Abbiamo raccolto alcune delle nostre destinazioni preferite incentrate sullo yoga e abbiamo incluso alcuni consigli per aiutarti a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":39949,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[1],"tags":[187],"class_list":["post-39948","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-senza-categoria","tag-vacanze-yoga"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vacanze Olistiche 2018: destinazioni in Italia - Eventi Yoga<\/title>\n<meta name=\"description\" content=\"Stai cercando una destinazione per una vacanza olistica? Qui trovi alcuni suggerimenti e le mete per le tue vacanze 2018.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vacanze Olistiche 2018: destinazioni in Italia - Eventi Yoga\" \/>\n<meta property=\"og:description\" content=\"Stai cercando una destinazione per una vacanza olistica? Qui trovi alcuni suggerimenti e le mete per le tue vacanze 2018.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"Eventi Yoga\" \/>\n<meta property=\"article:published_time\" content=\"2018-02-16T13:36:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-22T13:45:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/02\/Vacanze-Olistiche-2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Elena Petrunina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Elena Petrunina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/\",\"url\":\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/\",\"name\":\"Vacanze Olistiche 2018: destinazioni in Italia - Eventi Yoga\",\"isPartOf\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/02\/Vacanze-Olistiche-2018.jpg\",\"datePublished\":\"2018-02-16T13:36:00+00:00\",\"dateModified\":\"2022-02-22T13:45:25+00:00\",\"author\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/#\/schema\/person\/ff7e282f858c6f25b96e84f395450004\"},\"description\":\"Stai cercando una destinazione per una vacanza olistica? Qui trovi alcuni suggerimenti e le mete per le tue vacanze 2018.\",\"breadcrumb\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#primaryimage\",\"url\":\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/02\/Vacanze-Olistiche-2018.jpg\",\"contentUrl\":\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/02\/Vacanze-Olistiche-2018.jpg\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eventiyoga.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vacanze Olistiche 2018: destinazioni in Italia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/#website\",\"url\":\"https:\/\/eventiyoga.it\/blog\/\",\"name\":\"Eventi Yoga\",\"description\":\"Il portale Italiano per gli eventi dello yoga\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eventiyoga.it\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/#\/schema\/person\/ff7e282f858c6f25b96e84f395450004\",\"name\":\"Elena Petrunina\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8760e76687c89b2c8f079a98b908a440b7152ebe9b0fc336b996432343253efe?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8760e76687c89b2c8f079a98b908a440b7152ebe9b0fc336b996432343253efe?s=96&d=mm&r=g\",\"caption\":\"Elena Petrunina\"},\"description\":\"Yoga Marketing Coach &amp; Fondatrice di EventiYoga.it, il portale che ha connesso migliaia di insegnanti con oltre 1 milione di praticanti yoga in Italia. Aiuto insegnanti yoga a definire la loro unicit\u00e0, farsi trovare dalle persone giuste e creare programmi e ritiri yoga trasformativi e altamente richiesti.\",\"url\":\"https:\/\/eventiyoga.it\/blog\/author\/elena-petrunina\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vacanze Olistiche 2018: destinazioni in Italia - Eventi Yoga","description":"Stai cercando una destinazione per una vacanza olistica? Qui trovi alcuni suggerimenti e le mete per le tue vacanze 2018.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/","og_locale":"en_US","og_type":"article","og_title":"Vacanze Olistiche 2018: destinazioni in Italia - Eventi Yoga","og_description":"Stai cercando una destinazione per una vacanza olistica? Qui trovi alcuni suggerimenti e le mete per le tue vacanze 2018.","og_url":"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/","og_site_name":"Eventi Yoga","article_published_time":"2018-02-16T13:36:00+00:00","article_modified_time":"2022-02-22T13:45:25+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/02\/Vacanze-Olistiche-2018.jpg","type":"image\/jpeg"}],"author":"Elena Petrunina","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Elena Petrunina","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/","url":"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/","name":"Vacanze Olistiche 2018: destinazioni in Italia - Eventi Yoga","isPartOf":{"@id":"https:\/\/eventiyoga.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#primaryimage"},"image":{"@id":"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#primaryimage"},"thumbnailUrl":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/02\/Vacanze-Olistiche-2018.jpg","datePublished":"2018-02-16T13:36:00+00:00","dateModified":"2022-02-22T13:45:25+00:00","author":{"@id":"https:\/\/eventiyoga.it\/blog\/#\/schema\/person\/ff7e282f858c6f25b96e84f395450004"},"description":"Stai cercando una destinazione per una vacanza olistica? Qui trovi alcuni suggerimenti e le mete per le tue vacanze 2018.","breadcrumb":{"@id":"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#primaryimage","url":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/02\/Vacanze-Olistiche-2018.jpg","contentUrl":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/02\/Vacanze-Olistiche-2018.jpg","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/eventiyoga.it\/blog\/vacanze-olistiche-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eventiyoga.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Vacanze Olistiche 2018: destinazioni in Italia"}]},{"@type":"WebSite","@id":"https:\/\/eventiyoga.it\/blog\/#website","url":"https:\/\/eventiyoga.it\/blog\/","name":"Eventi Yoga","description":"Il portale Italiano per gli eventi dello yoga","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eventiyoga.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/eventiyoga.it\/blog\/#\/schema\/person\/ff7e282f858c6f25b96e84f395450004","name":"Elena Petrunina","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eventiyoga.it\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8760e76687c89b2c8f079a98b908a440b7152ebe9b0fc336b996432343253efe?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8760e76687c89b2c8f079a98b908a440b7152ebe9b0fc336b996432343253efe?s=96&d=mm&r=g","caption":"Elena Petrunina"},"description":"Yoga Marketing Coach &amp; Fondatrice di EventiYoga.it, il portale che ha connesso migliaia di insegnanti con oltre 1 milione di praticanti yoga in Italia. Aiuto insegnanti yoga a definire la loro unicit\u00e0, farsi trovare dalle persone giuste e creare programmi e ritiri yoga trasformativi e altamente richiesti.","url":"https:\/\/eventiyoga.it\/blog\/author\/elena-petrunina\/"}]}},"_links":{"self":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/posts\/39948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/comments?post=39948"}],"version-history":[{"count":0,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/posts\/39948\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/media\/39949"}],"wp:attachment":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/media?parent=39948"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/categories?post=39948"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/tags?post=39948"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}