{"id":45432,"date":"2022-07-05T11:50:48","date_gmt":"2022-07-05T09:50:48","guid":{"rendered":"https:\/\/eventiyoga.it\/blog\/?p=45432"},"modified":"2022-07-12T11:52:34","modified_gmt":"2022-07-12T09:52:34","slug":"yoga-per-gli-occhi","status":"publish","type":"post","link":"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/","title":{"rendered":"Yoga per gli occhi: esercizi yoga per migliorare la vista"},"content":{"rendered":"\n<p>Quante volte ti sei trovato a fine giornata con gli occhi affaticati, dolori alle palpebre e vista offuscata? Di certo, stare ore e ore davanti ai monitor del computer e dello smartphone non \u00e8 un toccasana per la vista: l&#8217;esposizione prolungata va infatti a inficiare il corretto funzionamento dei <strong><a aria-label=\"muscoli degli occhi  (opens in a new tab)\" href=\"https:\/\/it.wikipedia.org\/wiki\/Categoria:Muscoli_degli_occhi\" target=\"_blank\" rel=\"noreferrer noopener\" class=\"ek-link\">muscoli degli occhi <\/a><\/strong>e i <strong><a href=\"https:\/\/it.wikipedia.org\/wiki\/Fotorecettore\" target=\"_blank\" aria-label=\"fotorecettori (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"ek-link\">fotorecettori<\/a><\/strong>. Non ci crederai &#8211; in realt\u00e0 speriamo tu ci creda &#8211; ma lo yoga pu\u00f2 essere d&#8217;aiuto anche in questo caso. Come? Lo scopriamo in questo articolo, in cui parliamo di <strong>Yoga per gli occhi: esercizi yoga per migliorare la vista<\/strong>. Aguzza lo sguardo, buona lettura e&#8230; buona pratica! <\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_68_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#Yoga_per_gli_occhi_come_funziona\" title=\"Yoga per gli occhi, come funziona\">Yoga per gli occhi, come funziona<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#I_benefici_dello_yoga_per_la_vista\" title=\"I benefici dello yoga per la vista\">I benefici dello yoga per la vista<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#Esercizi_yoga_per_gli_occhi\" title=\"Esercizi yoga per gli occhi\">Esercizi yoga per gli occhi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#Rimedi_naturali_per_gli_occhi\" title=\"Rimedi naturali per gli occhi\">Rimedi naturali per gli occhi<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#Consigli_per_ridurre_laffaticamento_della_vista\" title=\"Consigli per ridurre l&#8217;affaticamento della vista\">Consigli per ridurre l&#8217;affaticamento della vista<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#Domande_frequenti\" title=\"Domande frequenti\">Domande frequenti<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#Letture_consigliate\" title=\"Letture consigliate\">Letture consigliate<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#Altre_risorse_interessanti_per_te\" title=\"Altre risorse interessanti per te\">Altre risorse interessanti per te<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#Scarica_lApp_Eventi_Yoga\" title=\"Scarica l\u2019App Eventi Yoga\">Scarica l\u2019App Eventi Yoga<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#Iscriviti_alla_newsletter\" title=\"Iscriviti alla newsletter\">Iscriviti alla newsletter<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-yoga-per-gli-occhi-come-funziona\"><span class=\"ez-toc-section\" id=\"Yoga_per_gli_occhi_come_funziona\"><\/span>Yoga per gli occhi, come funziona<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Iniziamo col dire che lo <strong>yoga per gli occhi<\/strong> \u00e8 una pratica non ancora molto diffusa, ma decisamente benefica: i suoi effetti vanno ad aggiungersi alla lunga schera di <strong><a href=\"https:\/\/eventiyoga.it\/blog\/yoga-i-benefici\/\" class=\"ek-link\">benefici <\/a><\/strong>che lo yoga procura alla mente e al corpo. Ma di cosa si tratta? In sostanza \u00e8 una vera e propria <strong>tecnica di rilassamento<\/strong> che, se praticata con costanza e continuit\u00e0, ti permette di <strong>non avvertire pi\u00f9 il senso di affaticamento e il dolore ai muscoli degli occhi<\/strong>. Consiste nell&#8217;eseguire determinati <strong>movimenti che vanno a irrobustire proprio questi muscoli<\/strong>. E la conseguenza del rafforzamento \u00e8 il sollievo a tutta la zona oculare. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"I_benefici_dello_yoga_per_la_vista\"><\/span>I benefici dello yoga per la vista<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Yoga occhi, ecco i principali benefici: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>riduce la pressione dell&#8217;occhio;<\/li><li>contribuisce a rafforzare la forza oculare;<\/li><li>migliora la capacit\u00e0 di messa a fuoco;<\/li><li>rilassa gli occhi e di conseguenza il senso di affaticamento si riduce notevolmente;<\/li><li>aiuta a prestare maggiore attenzione a ci\u00f2 che si vede, e quindi si avverte la sensazione di vedere in modo pi\u00f9 nitido e centrato.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-benefici-non-solo-agli-occhi\">Benefici non solo agli occhi <\/h3>\n\n\n\n<p>Oltre ai benefici agli occhi, gli <strong>esercizi di focalizzazione e allenamento dei muscoli oculari<\/strong><a href=\"https:\/\/www.my-personaltrainer.it\/fisiologia\/muscolo-scheletrico.html\" class=\"ek-link\"> <\/a>si rivelano efficaci anche per un <strong>rilassamento generale di tutto il corpo<\/strong>, che, proprio come lo yoga, aiutano a contrastare <strong><a href=\"https:\/\/eventiyoga.it\/blog\/yoga-e-attacchi-di-panico\/\" class=\"ek-link\">l&#8217;ansia<\/a><\/strong>, <strong><a href=\"https:\/\/eventiyoga.it\/blog\/yoga-contro-stress-esercizi-consigli-contro-stress-e-ansia\/\" class=\"ek-link\">lo stress<\/a><\/strong> e il <strong><a href=\"https:\/\/eventiyoga.it\/blog\/le-migliori-posizioni-yoga-contro-mal-testa\/\" class=\"ek-link\">mal di testa.<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Esercizi_yoga_per_gli_occhi\"><\/span>Esercizi yoga per gli occhi<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Eccoci al punto centrale del nostro articolo, con ben <strong>sei esercizi yoga per gli occhi<\/strong>. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Trataka<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Posizionati davanti a una candela accesa: la schiena ben dritta, la fiamma all\u2019altezza degli occhi.<\/li><li>Fissa il centro della fiamma, possibilmente senza mai sbattere le palpebre. Non \u00e8 facile, soprattuto le prime volte, ma provaci. <\/li><li>Continua per cinque minuti, anche se gli occhi ti lacrimano: \u00e8 il segno che si sta compiendo la pulizia dei dotti lacrimali.<\/li><li>A tempo terminato, chiudi e riapri gli occhi pi\u00f9 volte ed effettua qualche respiro a occhi chiusi.<\/li><\/ul>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/trataca.png\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/trataca-1024x1024.png\" alt=\"Trataca, lo yoga per gli occhi\" class=\"wp-image-45546\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/trataca-1024x1024.png\" alt=\"Trataca, lo yoga per gli occhi\" class=\"wp-image-45546\"\/><\/noscript><\/a><\/figure><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Messa a fuoco<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Seduto, schiena dritta, fissando la punta dell\u2019indice, porta il dito tra le sopracciglia.<\/li><li>Mantieni la posizione e lo sguardo per 3-4 respiri.<\/li><li>Sempre guardando l&#8217;indice, riportalo avanti a braccio totalmente disteso.<\/li><li>Dopo qualche respiro, riposiziona nuovamente il dito tra le sopracciglia.<\/li><li>Finita la sequenza, ripeterla partendo e ritornando alla punta del naso.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Messa a fuoco in movimento<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Siediti con la schiena dritta, sguardo davanti a te.<\/li><li>Allunga il braccio sinistro pi\u00f9 che puoi, con il pollice della mano verso l&#8217;alto.<\/li><li>Focalizzati sul pollice.<\/li><li>Muovi lentamente il braccio prima verso destra, fin dove riesci, e poi verso sinistra, sempre seguendo il pollice con gli occhi. Fai attenzione a non muovere il collo. &nbsp;&nbsp;&nbsp;&nbsp;<\/li><li>Ripeti pi\u00f9 volte.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Rotazione degli occhi<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>La posizione di partenza anche di questo esercizio yoga per occhi, \u00e8 sempre la medesima: seduto con la schiena dritta.<\/li><li>Guarda il soffitto, cercando di mantenere il pi\u00f9 possibile la concentrazione.<\/li><li>Dopodich\u00e9 ruota gli occhi verso destra, poi in alto, poi a sinistra.<\/li><li>Riporta lo sguardo al soffitto.<\/li><li>Torna a guardare davanti.<\/li><li>Ripeti pi\u00f9 volte la rotazione in questa direzione, poi muovi gli occhi in senso antiorario seguendo lo stesso principio.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Decentramento<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Stendi entrambe le braccia in avanti, con i pollici alzati.<\/li><li>Fissando il centro dei due pollici, apri le braccia lateralmente, molto, molto lentamente. Fai attenzione a non muovere la testa.<\/li><li>Mantieni la posizione per 6-7 respiri, poi torna alla posizione iniziale, sempre seguendo il movimento con gli occhi.<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Sguardo in verticale<\/h3>\n\n\n\n<ul class=\"wp-block-list\"><li>Stendi il braccio destro in avanti, puntando l\u2019indice verso sinistra.<\/li><li>Con lo sguardo fisso sul centro del dito, solleva il braccio. \u00c8 importante anche in questo caso non muovere la testa.<\/li><li>Prosegui a sollevarlo finch\u00e9 non scompare dal campo visivo.<\/li><li>Mantieni la posizione per 3-4 respiri, dopodich\u00e9 riabbassa il dito all\u2019altezza degli occhi.<\/li><li>Ripeti tutto, spostando il dito verso il basso.<\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Rimedi_naturali_per_gli_occhi\"><\/span>Rimedi naturali per gli occhi<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ecco qui una serie di rimedi per aiutare gli occhi a <strong>non essere affaticati e doloranti<\/strong>. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I cibi che aiutano a migliorare la vista<\/h3>\n\n\n\n<p>La <strong>vitamina A<\/strong> e la <strong>luteina <\/strong>sono due elementi che aiutano a fare stare meglio gli occhi. Ecco alcuni alimenti che le contengono: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>carote, spinaci e cavoli (vitamina A e luteina);<\/li><li>zucchine, bietole e cavoletti di Bruxelles (luteina);<\/li><li>patate dolci e burro (vitamina A); occhio al burro, \u00e8 amico della vista ma nemico del colesterolo;<\/li><li>fegato (vitamina A), incluso l&#8217;olio di fegato di merluzzo;<\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Rimedi erboristici per migliorare la vista<\/h3>\n\n\n\n<p>Ecco qui alcune delle <strong>erbe benefiche per la salute degli occhi<\/strong>: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>camomilla: decongestionante e idratante;<\/li><li>mirtillo: migliora la vista e viene utilizzato per i disturbi della retina e per il trattamento della cataratta;<\/li><li>malva: emoliente e lenitiva, agevola l&#8217;idratazione dell&#8217;occhio ed \u00e8 ideale per chi \u00e8 fotosensibile e per chi indossa abitualmente le lenti a contatto:<\/li><li>Ginkgo Biloba: antiossidante, aiuta la circolazione e viene assunto per la cura del glaucoma e la degenarazione maculare; <\/li><li>calendula: disinfiammante, \u00e8 tra gli ingredienti pi\u00f9 diffusi nei colliri lenitivi. <\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Altri rimedi naturali per una vista migliore<\/h3>\n\n\n\n<p>Oltre a quanto scritto, ricordiamo anche altre <strong>buone pratiche che possano alleviare la stanchezza degli occhi<\/strong>: <\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>spruzzare acqua fredda sugli occhi aperti; <\/li><li>effettuare il palming, ossia mettere le mani riscaldate (sfregandole tra di loro) a coppa sugli occhi senza toccarli e restare cos\u00ec per una decina di respiri;<\/li><li>se stai tante ore davanti a un monitor, distogliere lo sguardo ogni tanto, fa bene. <\/li><\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Precauzioni e controindicazioni <\/h3>\n\n\n\n<p>Considera questi esercizi come <strong>un momento di rilassamento, un momento per te<\/strong>. Trova un posto dove possa <strong>sederti comodamente mantenendo la schienza ben dritta<\/strong>. <\/p>\n\n\n\n<p>Come per lo yoga, a premiare \u00e8 la costanza, se riuscissi a ritagliarti qualche minuto tutti i giorni, i benefici sarebbero subito tangibili. <\/p>\n\n\n\n<p>Importante: gli esercizi yoga per gli occhi devono essere eseguiti <strong>senza indossare gli occhiali e le lenti a contatto<\/strong>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Consigli_per_ridurre_laffaticamento_della_vista\"><\/span>Consigli per ridurre l&#8217;affaticamento della vista<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>La maggior parte dei problemi di affaticamento della vista sono dovuti, come gi\u00e0 scritto, <strong>all&#8217;esposizione troppo prolungata davanti ai monitor<\/strong>. Il consiglio pi\u00f9 prezioso che potremmo darti \u00e8 quello di stare il pi\u00f9 possibile all&#8217;aperto e offline. Ma visto che ci rendiamo conto che spesso questo non \u00e8 contemplabile, ti suggeriamo di prenderti degli spazi per te, basta poco: <strong>ogni tanto distogli lo sguardo, guarda fuori dalla finestra, rinfrescati<\/strong>. <\/p>\n\n\n\n<p>Insomma, <strong>prenditi cura di te anche quando devi pensare ad altro.<\/strong> <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/corsi.eventiyoga.it\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/04\/banner-portale-corsi-yoga.jpg\" alt=\"Scuola Yoga Online di Eventi Yoga - Lezioni e Corsi di Yoga On Line\" class=\"wp-image-42756\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/04\/banner-portale-corsi-yoga.jpg\" alt=\"Scuola Yoga Online di Eventi Yoga - Lezioni e Corsi di Yoga On Line\" class=\"wp-image-42756\"\/><\/noscript><\/a><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Domande_frequenti\"><\/span>Domande frequenti<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>Cosa si pu\u00f2 fare per migliorare la vista?<\/strong><\/p>\n\n\n\n<p>Oltre ad andare periodicamente dall&#8217;oculista e sottoporti a controlli, puoi praticare yoga per gli occhi, una serie di esercizi pensati proprio per alleviare i disturbi oculari. <\/p>\n\n\n\n<p id=\"h-cosa-bisogna-fare-per-rilassare-i-muscoli-oculari\"><strong>Cosa bisogna fare per rilassare i muscoli oculari?<\/strong><\/p>\n\n\n\n<p>Praticare le tecniche di rilassamento descritte sopra, sono ben sei esercizi yoga per gli occhi. <\/p>\n\n\n\n<p><strong>Lo yoga pu\u00f2 aiutare a migliorare la vista?<\/strong><\/p>\n\n\n\n<p>S\u00ec, pu\u00f2 aiutare a migliorare la messa a fuoco e a rafforzare i muscoli degli occhi. <\/p>\n\n\n\n<p><strong>I benefici degli esercizi yoga si notano subito?<\/strong><\/p>\n\n\n\n<p>Come per lo yoga, si notano se li pratichi con costanza e continuit\u00e0. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Letture_consigliate\"><\/span>Letture consigliate <span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong><a href=\"https:\/\/www.macrolibrarsi.it\/libri\/__lo-yoga-per-gli-occhi-kazuhiro-nakagawa-libro.php?pn=5628\" target=\"_blank\" aria-label=\" (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"ek-link\">Recupera una vista perfetta con lo yoga per gli occhi <\/a><\/strong>di Kazuhiro Nakagawa: il metodo naturale del dottor Nakagawa, direttore del Vision Fitness Center di Tokyo, offre un grande aiuto per tutti i problemi visivi. Si tratta di un sistema testato su moltissimi pazienti che comprende semplici esercizi e un training mentale basato sul rivoluzionario concetto che la capacit\u00e0 visiva non dipende solo dagli occhi ma in realt\u00e0 risiede nel cervello. <\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.macrolibrarsi.it\/libri\/__lo-yoga-per-gli-occhi-kazuhiro-nakagawa-libro.php?pn=5628\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/Recupera-una-vista-perfetta-con-lo-yoga-per-gli-occhi.jpg\" alt=\"Recupera una vista perfetta con lo yoga per gli occhi\" class=\"wp-image-45466\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/Recupera-una-vista-perfetta-con-lo-yoga-per-gli-occhi.jpg\" alt=\"Recupera una vista perfetta con lo yoga per gli occhi\" class=\"wp-image-45466\"\/><\/noscript><\/a><\/figure><\/div>\n\n\n\n<p><strong><a href=\"https:\/\/www.macrolibrarsi.it\/libri\/__yoga-per-gli-occhi.php?pn=5628\" target=\"_blank\" aria-label=\" (opens in a new tab)\" rel=\"noreferrer noopener\" class=\"ek-link\">Yoga per gli occhi <\/a><\/strong>di Christiansen Andrea: scopri i semplici esercizi che derivano dallo yoga e quelli ideati dal dottor William Bates, il pioniere dell\u2019educazione visiva, per rilassare gli occhi, ripristinare la flessibilit\u00e0 dei muscoli oculari e rafforzare cos\u00ec la tua vista. Potrai arrestare sia un principio di presbiopia, sia di miopia e migliorare considerevolmente i difetti visivi di lunga data. Facendo yoga per gli occhi, non solo comprenderai meglio come percepisci il mondo attraverso i tuoi occhi, ma \u00e8 molto probabile che tu veda te stesso in una nuova luce.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.macrolibrarsi.it\/libri\/__yoga-per-gli-occhi.php?pn=5628\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/Yoga-per-gli-occhi.jpg\" alt=\"Yoga per gli occhi\" class=\"wp-image-45468\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/Yoga-per-gli-occhi.jpg\" alt=\"Yoga per gli occhi\" class=\"wp-image-45468\"\/><\/noscript><\/a><\/figure><\/div>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Altre_risorse_interessanti_per_te\"><\/span>Altre risorse interessanti per te<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><a href=\"https:\/\/eventiyoga.it\/blog\/yoga-e-salute\/\" target=\"_blank\" rel=\"noreferrer noopener\">Yoga e Salute: perch\u00e9 praticare yoga fa bene<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-migliorare-la-digestione\/\" class=\"ek-link\">Yoga per migliorare la digestione: benefici e posizioni<\/a><\/p>\n\n\n\n<p><a href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-cervicale\/\" class=\"ek-link\">Yoga per cervicale: esercizi yoga per il collo<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><span class=\"ez-toc-section\" id=\"Scarica_lApp_Eventi_Yoga\"><\/span>Scarica l\u2019App Eventi Yoga<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Il pi\u00f9 grande catalogo degli eventi di yoga in Italia di Eventiyoga.it sempre a portata di mano! Centinaia di vacanze, ritiri, viaggi e corsi di yoga per tutti i gusti da scegliere con un click. Per trovare la proposta ideale per te, prenotare subito e godere dei benefici della <a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-2\/\">vacanza yoga<\/a> e meditazione.<\/p>\n\n\n\n<p class=\"has-text-align-center\">Scarica ora l\u2019app EventiYoga<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/09\/scarica_app_eventiyoga-1.jpg\" alt=\"Scegliere un ritiro yoga: scarica l'App EventiYoga per prenotare il tuo prossimo viaggio \" class=\"wp-image-23454\"\/><noscript><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/09\/scarica_app_eventiyoga-1.jpg\" alt=\"Scegliere un ritiro yoga: scarica l'App EventiYoga per prenotare il tuo prossimo viaggio \" class=\"wp-image-23454\" srcset=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/09\/scarica_app_eventiyoga-1.jpg 1024w, https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/09\/scarica_app_eventiyoga-1-300x225.jpg 300w, https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/09\/scarica_app_eventiyoga-1-768x576.jpg 768w, https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/09\/scarica_app_eventiyoga-1-200x150.jpg 200w, https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/09\/scarica_app_eventiyoga-1-600x450.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/noscript><\/figure>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/apps.apple.com\/us\/app\/id1514783292\" target=\"_blank\" aria-label=\" (opens in a new tab)\" rel=\"noreferrer noopener sponsored\" class=\"ek-link\">App Eventi Yoga per iOS<\/a><\/p>\n\n\n\n<p class=\"has-text-align-center\"><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.maugry.yoga\" target=\"_blank\" aria-label=\" (opens in a new tab)\" rel=\"noreferrer noopener sponsored\" class=\"ek-link\">App Eventi Yoga per Android<\/a><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-iscriviti-alla-newsletter\"><span class=\"ez-toc-section\" id=\"Iscriviti_alla_newsletter\"><\/span>Iscriviti alla newsletter<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Resta sempre aggiornato sulle iniziative <a href=\"https:\/\/eventiyoga.it\/blog\/vacanze-yoga-italia-consigli\/\">yoga in Italia<\/a>. Sei alle prime armi con lo yoga, un praticante o un insegnante? Inviamo ogni settimana solo notizie rilevanti per te!<\/p>\n\n\n\n<figure class=\"wp-block-image caption-align-center\"><a href=\"https:\/\/eventiyoga.it\/blog\/newsletter-eventi-yoga\/\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/10\/Banner-Iscrizione-NL.jpg\" alt=\"Iscriviti alla Newsletter \u2013 Per te subito un Bonus!\" class=\"wp-image-16731\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/10\/Banner-Iscrizione-NL.jpg\" alt=\"Iscriviti alla Newsletter \u2013 Per te subito un Bonus!\" class=\"wp-image-16731\"\/><\/noscript><\/a><figcaption>Iscriviti alla Newsletter \u2013 Per te subito un Bonus!<\/figcaption><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quante volte ti sei trovato a fine giornata con gli occhi affaticati, dolori alle palpebre e vista offuscata? Di certo, stare ore e ore davanti ai monitor del computer e dello smartphone non \u00e8 un toccasana per la vista: l&#8217;esposizione prolungata va infatti a inficiare il corretto funzionamento dei muscoli degli occhi e i fotorecettori. [&hellip;]<\/p>\n","protected":false},"author":363,"featured_media":45433,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":7,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[137,41],"tags":[38,44008],"class_list":["post-45432","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-benessere","category-tips","tag-praticare-yoga","tag-yoga-per-gli-occhi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Yoga per gli occhi: esercizi yoga per migliorare la vista | Eventi Yoga<\/title>\n<meta name=\"description\" content=\"Yoga per gli occhi: esercizi yoga per migliorare la vista. Cosa e come fare per alleviare i disturbi agli occhi con la pratica yoga.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Yoga per gli occhi: esercizi yoga per migliorare la vista | Eventi Yoga\" \/>\n<meta property=\"og:description\" content=\"Yoga per gli occhi: esercizi yoga per migliorare la vista. Cosa e come fare per alleviare i disturbi agli occhi con la pratica yoga.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/\" \/>\n<meta property=\"og:site_name\" content=\"Eventi Yoga\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-05T09:50:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-12T09:52:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/Yoga_per_occhI_esercizi_FACEBOOK.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/\",\"url\":\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/\",\"name\":\"Yoga per gli occhi: esercizi yoga per migliorare la vista | Eventi Yoga\",\"isPartOf\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/Yoga_per_occhI_esercizi_FACEBOOK.png\",\"datePublished\":\"2022-07-05T09:50:48+00:00\",\"dateModified\":\"2022-07-12T09:52:34+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Yoga per gli occhi: esercizi yoga per migliorare la vista. Cosa e come fare per alleviare i disturbi agli occhi con la pratica yoga.\",\"breadcrumb\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#primaryimage\",\"url\":\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/Yoga_per_occhI_esercizi_FACEBOOK.png\",\"contentUrl\":\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/Yoga_per_occhI_esercizi_FACEBOOK.png\",\"width\":1024,\"height\":768,\"caption\":\"yoga per gli occhi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eventiyoga.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Yoga per gli occhi: esercizi yoga per migliorare la vista\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/#website\",\"url\":\"https:\/\/eventiyoga.it\/blog\/\",\"name\":\"Eventi Yoga\",\"description\":\"Il portale Italiano per gli eventi dello yoga\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eventiyoga.it\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/eventiyoga.it\/blog\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Yoga per gli occhi: esercizi yoga per migliorare la vista | Eventi Yoga","description":"Yoga per gli occhi: esercizi yoga per migliorare la vista. Cosa e come fare per alleviare i disturbi agli occhi con la pratica yoga.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/","og_locale":"en_US","og_type":"article","og_title":"Yoga per gli occhi: esercizi yoga per migliorare la vista | Eventi Yoga","og_description":"Yoga per gli occhi: esercizi yoga per migliorare la vista. Cosa e come fare per alleviare i disturbi agli occhi con la pratica yoga.","og_url":"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/","og_site_name":"Eventi Yoga","article_published_time":"2022-07-05T09:50:48+00:00","article_modified_time":"2022-07-12T09:52:34+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/Yoga_per_occhI_esercizi_FACEBOOK.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/","url":"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/","name":"Yoga per gli occhi: esercizi yoga per migliorare la vista | Eventi Yoga","isPartOf":{"@id":"https:\/\/eventiyoga.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#primaryimage"},"image":{"@id":"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#primaryimage"},"thumbnailUrl":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/Yoga_per_occhI_esercizi_FACEBOOK.png","datePublished":"2022-07-05T09:50:48+00:00","dateModified":"2022-07-12T09:52:34+00:00","author":{"@id":""},"description":"Yoga per gli occhi: esercizi yoga per migliorare la vista. Cosa e come fare per alleviare i disturbi agli occhi con la pratica yoga.","breadcrumb":{"@id":"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#primaryimage","url":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/Yoga_per_occhI_esercizi_FACEBOOK.png","contentUrl":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2022\/07\/Yoga_per_occhI_esercizi_FACEBOOK.png","width":1024,"height":768,"caption":"yoga per gli occhi"},{"@type":"BreadcrumbList","@id":"https:\/\/eventiyoga.it\/blog\/yoga-per-gli-occhi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eventiyoga.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Yoga per gli occhi: esercizi yoga per migliorare la vista"}]},{"@type":"WebSite","@id":"https:\/\/eventiyoga.it\/blog\/#website","url":"https:\/\/eventiyoga.it\/blog\/","name":"Eventi Yoga","description":"Il portale Italiano per gli eventi dello yoga","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eventiyoga.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"","url":"https:\/\/eventiyoga.it\/blog\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/posts\/45432","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/users\/363"}],"replies":[{"embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/comments?post=45432"}],"version-history":[{"count":0,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/posts\/45432\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/media\/45433"}],"wp:attachment":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/media?parent=45432"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/categories?post=45432"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/tags?post=45432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}