{"id":6384,"date":"2017-09-29T00:44:41","date_gmt":"2017-09-28T22:44:41","guid":{"rendered":"https:\/\/eventiyoga.it\/blog\/?p=6384"},"modified":"2022-12-01T11:49:25","modified_gmt":"2022-12-01T10:49:25","slug":"asana-yoga-benefici-e-precauzioni","status":"publish","type":"post","link":"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/","title":{"rendered":"Asana yoga: benefici e precauzioni da adottare nella pratica"},"content":{"rendered":"\n<p>Come diceva il Maestro Pattabhi Jois, <strong>Yoga \u00e8 99% pratica ed 1% teoria.<\/strong> La pratica degli asana yoga \u00e8 la parte pi\u00f9 conosciuta dello Yoga e chi pratica sa che gli asana non sono solo esercizio fisico ma creano benessere nel corpo e nella mente cos\u00ec come una maggiore apertura mentale e spirituale accompagnando il cammino di chi pratica.<\/p>\n\n\n\n<p>Gli asana yoga possono essere divise per \u201cfamiglie\u201d ovvero, gruppi di asana con una simile interazione fisica e simili benefici. Nel corpo gli effetti degli asana sono spesso localizzati all\u2019area interessata. Nel corpo sottile, il prana che scorre e fluisce nel corpo attraverso i canali energetici porta beneficio ad un livello pi\u00f9 profondo, emozionale, spirituale, energetico e molto di pi\u00f9.<br>La pratica degli Asana ha due scopi: fisico preparando il corpo alla posizione finale del loto, la posizione della meditazione e quello pi\u00f9 sottile di pulire le \u201cnadi\u201d i canali energetici per far fluire il prana in modo sano e fluido per mantenere il corpo nuovo e sano.<\/p>\n\n\n\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_68_1 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title \" >Indice<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#I_benefici_e_le_precauzioni_da_adottare_per_ogni_famiglia_di_asana_yoga\" title=\"I benefici e le precauzioni da adottare per ogni famiglia di asana yoga\">I benefici e le precauzioni da adottare per ogni famiglia di asana yoga<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#Letture_consigliate\" title=\"Letture consigliate\">Letture consigliate<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#Corsi_Yoga_Consigliati_da_Eventiyoga\" title=\"Corsi Yoga Consigliati da Eventiyoga\">Corsi Yoga Consigliati da Eventiyoga<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#Tre_risorse_interessanti_per_te\" title=\"Tre risorse interessanti per te\">Tre risorse interessanti per te<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#Iscriviti_alla_nostra_newsletter\" title=\"Iscriviti alla nostra newsletter\">Iscriviti alla nostra newsletter<\/a><\/li><\/ul><\/nav><\/div>\n<h2 class=\"wp-block-heading\" id=\"h-i-benefici-e-le-precauzioni-da-adottare-per-ogni-famiglia-di-asana-yoga\"><span class=\"ez-toc-section\" id=\"I_benefici_e_le_precauzioni_da_adottare_per_ogni_famiglia_di_asana_yoga\"><\/span>I benefici e le precauzioni da adottare per ogni famiglia di asana yoga<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-asana-yoga-torsioni\">Asana yoga: Torsioni<\/h3>\n\n\n\n<p>Le torsioni che siano effettuate da seduti a terra o in piedi sono ottime per effettuare un massaggio agli organi interni per mantenerli giovani e vitali. \u00c8 importante seguire l\u2019anatomia del colon e per questo \u00e8 indicato effettuare la prima torsione sempre verso destra per poi aprire verso sinistra. Alleate della dieta, di chi soffre di intestino pigro e per le persone che stanno affrontando un periodo di detox. Aiutano inoltre ad estendere i lati del corpo e a riequilibrare la colonna dopo una classe per questo \u00e8 buono effettuarle sempre anche prima di <strong><a href=\"https:\/\/eventiyoga.it\/blog\/savasana\/\">Savasana<\/a><\/strong>. A livello sottile le torsioni aprono a nuovi orizzonti aiutando ad aumentare la prospettiva. Ci\u00f2 che \u00e8 nuovo sempre crea entusiasmo e timore al tempo stesso, le torsioni aiutano a preparare la mente ad aprirsi al nuovo con coraggio e senza paure.<\/p>\n\n\n\n<p><strong>Precauzioni<\/strong>: durante la gravidanza ed i giorni <a href=\"https:\/\/eventiyoga.it\/blog\/ridurre-i-dolori-mestruali-con-lo-yoga\/\" class=\"ek-link\">mestruali<\/a> non esagerare nella torsione.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-asana-yoga-piegamenti-in-avanti\">Asana yoga: Piegamenti in avanti<\/h3>\n\n\n\n<p>Si definiscono piegamenti in avanti quelle posizioni effettuate seduti a terra dove il corpo si muove in avanti in direzione delle gambe. Queste posizioni si effettuano nell\u2019ultima parte di una lezione di Yoga quando si ha bisogno di calmare il corpo prima del Savasana finale. I piegamenti in avanti sono posizioni che a livello fisico aiutano la flessibilit\u00e0, allungano i muscoli delle gambe e della schiena. A livello sottile raffreddano il corpo e lo avvicinano alla terra. Riequilibrano il chakra della terra, Muladhara e sono indicate durante i giorni di mestruo. Queste asana aiutano inoltre a rilassare e calmare la mente soprattutto se effettuate con gli occhi chiusi, abbassano la temperatura del corpo e la pressione del sangue.<\/p>\n\n\n\n<p><strong>Precauzioni<\/strong>: durante la gravidanza effettuare in maniera non accentuata e mantenendo le gambe divaricate. Attenzione in caso di ernia posteriore del disco.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-asana-yoga-aperture-del-cuore\">Asana yoga: Aperture del cuore<\/h3>\n\n\n\n<p>Le aperture del cuore sono le posizioni che allungano la parte anteriore del corpo piegandolo all\u2019indietro. Sono tra le <a href=\"https:\/\/eventiyoga.it\/blog\/posizioni-yoga-illustrate\/\" class=\"ek-link\">posizioni<\/a> che creano maggior timore perch\u00e8 aprono ed offrono all\u2019esterno ci\u00f2 che pi\u00f9 spesso nascondiamo, il nostro cuore. Queste Asana allungano la parte frontale del corpo, gli addominali e rafforzano i quadricipiti ed aprono la cassa toracica per migliorare la respirazione. A livello energetico aiutano timidezza e depressione, sono di sostegno a molte terapie di trattamento di un trauma emozionale.<\/p>\n\n\n\n<p><strong>Precauzioni<\/strong>: da evitare in caso di gravidanza avanzata, in casi di periodo mestruale quelle con il contatto della pancia a terra per evitare compressione. Attenzione in caso di ernia anteriore del disco.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/eventiyoga.it\/blog\/urdhva-dhanurasana-tutto-sulla-posizione-dell-arco\/\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/11\/Urdhva-Dhanurasana_Facebook-1024x768.png\" alt=\"\" class=\"wp-image-17538 size-full\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/11\/Urdhva-Dhanurasana_Facebook-1024x768.png\" alt=\"\" class=\"wp-image-17538 size-full\"\/><\/noscript><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-large-font-size\"><a href=\"https:\/\/eventiyoga.it\/blog\/urdhva-dhanurasana-tutto-sulla-posizione-dell-arco\/\" class=\"ek-link\">Urdhva Dhanurasana<\/a><\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-asana-yoga-inversioni\">Asana yoga: Inversioni<\/h3>\n\n\n\n<p>Queste posizioni cambiano completamente la gravit\u00e0 del corpo regalando giovinezza e bellezza. Invertendo il corpo cambia il flusso del sangue migliorando la circolazione sanguigna, le funzioni mentali come concentrazione e memoria regalando pi\u00f9 ossigeno al cervello. Si energizza inoltre il corpo nelle inversioni pi\u00f9 intense mentre in quelle pi\u00f9 leggere si rilassa mente e corpo. La posizione con le gambe sollevate al muro (<a href=\"https:\/\/eventiyoga.it\/blog\/viparita-karani\/\">Viparita Karani<\/a>) \u00e8 ottima alleata delle caviglie e gambe gonfie. Migliora inoltre l\u2019equilibrio e rafforza la fiducia in se stessi aiutando ad affrontare le paure. Sono ottime durante un pomeriggio pigro e monotono per recuperare energia, per la sera prima di andare a dormire appoggiando i piedi alla parete e rimanere 15 minuti cos\u00ec, leggendo un libro. Sono adatte a tutti e divertenti per tutte le et\u00e0.<\/p>\n\n\n\n<p><strong>Precauzioni<\/strong>: attenzione a chi soffre di emicrania, di pressione oculare alta e per la gravidanza. In tutti e tre i casi le inversioni da effettuare sono pi\u00f9 leggere.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/03\/Viparita-Karani-FB-1024x768.png\" alt=\"\" class=\"wp-image-16648 size-full\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2016\/03\/Viparita-Karani-FB-1024x768.png\" alt=\"\" class=\"wp-image-16648 size-full\"\/><\/noscript><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-large-font-size\"><meta charset=\"utf-8\">Viparita Karani<\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-asana-yoga-posizioni-di-equilibrio\">Asana yoga: Posizioni di equilibrio<\/h3>\n\n\n\n<p>Le posizioni su una solo gamba aiutano a cambiare il centro di gravit\u00e0 per sviluppare stabilit\u00e0 e precisione. Con le posizione di equilibrio si aiuta la mente a concentrarsi e il corpo diventa pi\u00f9 forte. Queste asana sviluppano forza nelle caviglie e creano una solida e resistente base del corpo rafforzando inoltre le articolazioni ed i muscoli delle gambe. Adatte ad ogni livello e per ogni fisico, queste posizioni aiutano l\u2019equilibrio non solo fisico ma anche emotivo e spirituale apprendendo a cadere e rialzarsi, a cambiare il centro di gravit\u00e0 e riadattare il corpo e la mente sia fuori che dentro il <strong><a href=\"https:\/\/www.reyoga.it\/shop\/it\/36-tappetini-yoga?ry=3\">tappetino<\/a><\/strong>.<\/p>\n\n\n\n<p><strong>Precauzioni<\/strong>: in caso di et\u00e0 o gravidanza avanzate, il supporto di un muro pu\u00f2 aiutare.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-asana-yoga-equilibrio-sulle-mani\">Asana yoga: Equilibrio sulle mani<\/h3>\n\n\n\n<p>Queste posizioni sviluppano forza nella parte superiore del corpo e negli addominali, aiutano a rafforzare le articolazioni delle mani e dei polsi ed i muscoli delle braccia e spalle. A livello pi\u00f9 sottile aiutano la concentrazione e la disciplina mentale. Le posizioni di equilibrio sulle mani riscaldano il corpo rafforzandolo e rendendolo pi\u00f9 flessibile al tempo stesso. Sono un gran divertimento da provare anche in casa ed in famiglia. Con queste asana inoltre si affronta la paura universale del cadere scoprendo al tempo stesso la leggerezza e la calma del corpo in aria.<\/p>\n\n\n\n<p><strong>Precauzioni<\/strong>: in caso di problemi ai polsi, gomiti o spalle attendere che diminuisca l\u2019infiammazione per poter effettuare le posizioni.<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/02\/Kakasana_Facebook-1024x768.png\" alt=\"Kakasana\" class=\"wp-image-19365 size-full\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/02\/Kakasana_Facebook-1024x768.png\" alt=\"Kakasana\" class=\"wp-image-19365 size-full\"\/><\/noscript><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-large-font-size\"><meta charset=\"utf-8\"><a href=\"https:\/\/eventiyoga.it\/blog\/kakasana-tutto-sulla-posizione-del-corvo\/\" class=\"ek-link\">Kakasana<\/a><\/p>\n<\/div><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-asana-yoga-posizioni-di-forza\">Asana yoga: Posizioni di forza<\/h3>\n\n\n\n<p>Si intende per posizioni di forza quelle asana che usano il \u201ccore\u201d ovvero i muscoli centrali del corpo per sostenere la posizione, un esempio \u00e8 <strong>navasana<\/strong>, la posizione della barca. Queste posizioni aiutano la concentrazione, la disciplina e la determinazione. A livello fisico sviluppano <a href=\"https:\/\/eventiyoga.it\/blog\/come-sviluppare-addominali-con-lo-yoga\/\"><strong>forza negli addominali<\/strong><\/a> ed in tutto il corpo, aumentano la temperatura e bruciano grassi. Da effettuare in ogni lezione a qualsiasi livello aiutano a mantenere gli addominali forti per sostenere il corpo durante l\u2019intera pratica delle Asana.<\/p>\n\n\n\n<p><strong>Precauzioni<\/strong>: in caso di gravidanza avanzata \u00e8 meglio evitare di lavorare sui muscoli addominali centrali, meglio lavorare sui laterali in quanto necessari per sostenere il peso del ventre che cresce.<\/p>\n\n\n\n<p>La regola generale per praticare \u00e8 sempre la stessa: in caso di infiammazione, muscolare o articolare, \u00e8 meglio evitare la posizione mentre invece quando l\u2019infiammazione \u00e8 passata gli asana sono ottimi per aiutare a guarire un trauma e sono perfette per la prevenzione di qualsiasi tipo. (<em>Leggi anche<\/em>: <a href=\"https:\/\/eventiyoga.it\/blog\/dolori_durante_asana_cosa_fare\/\">Dolore durante la pratica delle asana: cosa fare?<\/a>)<\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/02\/Navasana_Facebook.jpg\" alt=\"Navasana\" class=\"wp-image-32080 size-full\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2020\/02\/Navasana_Facebook.jpg\" alt=\"Navasana\" class=\"wp-image-32080 size-full\"\/><\/noscript><\/figure><div class=\"wp-block-media-text__content\">\n<p class=\"has-large-font-size\">Navasana<\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-letture-consigliate\"><span class=\"ez-toc-section\" id=\"Letture_consigliate\"><\/span>Letture consigliate<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong>Yoga Terapeutico<\/strong>, anatomia completa delle posizioni (Ray Long): un testo per chi vuole saperne di pi\u00f9 su posizioni e anatomia del corpo umano nella pratica yoga.<\/p>\n\n\n\n<figure class=\"wp-block-image caption-align-center\"><a href=\"https:\/\/www.amazon.it\/terapeutico-Anatomia-completa-delle-posizioni\/dp\/8895687663\/ref=as_li_ss_tl?__mk_it_IT=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;crid=31XS2MTO0V9AR&amp;keywords=yoga+terapeutico&amp;qid=1573202405&amp;s=books&amp;sprefix=yoga+tera,aps,173&amp;sr=1-1&amp;linkCode=sl1&amp;tag=wwweventiyoit-21&amp;linkId=1cc2281f213fb908fcd0efe4956ba241&amp;language=it_IT\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/10\/YOGA-TERAPEUTICO-Prodotti-Blog-1024x700.png\" alt=\"\" class=\"wp-image-16504\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/10\/YOGA-TERAPEUTICO-Prodotti-Blog-1024x700.png\" alt=\"\" class=\"wp-image-16504\"\/><\/noscript><\/a><figcaption>Yoga Terapeutico di Ray Long<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background\" href=\"https:\/\/www.amazon.it\/terapeutico-Anatomia-completa-delle-posizioni\/dp\/8895687663\/ref=as_li_ss_tl?__mk_it_IT=%C3%85M%C3%85%C5%BD%C3%95%C3%91&amp;crid=31XS2MTO0V9AR&amp;keywords=yoga+terapeutico&amp;qid=1573202405&amp;s=books&amp;sprefix=yoga+tera,aps,173&amp;sr=1-1&amp;linkCode=sl1&amp;tag=wwweventiyoit-21&amp;linkId=1cc2281f213fb908fcd0efe4956ba241&amp;language=it_IT\" style=\"background-color:#d82098\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Acquista Yoga Terapeutico<\/strong><\/a><\/div>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-corsi-yoga-consigliati-da-eventiyoga\"><span class=\"ez-toc-section\" id=\"Corsi_Yoga_Consigliati_da_Eventiyoga\"><\/span>Corsi Yoga Consigliati da Eventiyoga<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p>Ecco alcuni corsi yoga online che consigliamo per imparare la corretta esecuzione degli asana per praticare in sicurezza e senza dolore.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-corso-completo-di-anatomia-dello-yoga\"><a href=\"https:\/\/eventiyoga.it\/blog\/prodotto\/corso-completo-anatomia-dello-yoga\/\">Corso Completo di Anatomia dello Yoga<\/a><\/h3>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/eventiyoga.it\/blog\/prodotto\/corso-completo-anatomia-dello-yoga\/\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2021\/08\/corso_anatomia-e-fisiologia_yoga.jpg\" alt=\"Corso completo di anatomia e fisiologia dello yoga\" class=\"wp-image-34625 size-full\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2021\/08\/corso_anatomia-e-fisiologia_yoga.jpg\" alt=\"Corso completo di anatomia e fisiologia dello yoga\" class=\"wp-image-34625 size-full\"\/><\/noscript><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p>Il&nbsp;<strong>Corso<\/strong><strong> Completo di <a href=\"https:\/\/eventiyoga.it\/blog\/anatomia-yoga\/\">Anatomia<\/a> e Fisiologia dello Yoga&nbsp;<\/strong>ti aiuta con:<\/p>\n\n\n\n<p>&nbsp;spiegazioni semplici e consigli per la corretta esecuzione delle asana,<\/p>\n\n\n\n<p>&nbsp;cosa fare e come evitare gli errori,<\/p>\n\n\n\n<p>&nbsp;i benefici che offrono gli asana e le controindicazioni,<\/p>\n\n\n\n<p>&nbsp;le tecniche di respirazione pi\u00f9 appropriate,<\/p>\n\n\n\n<p>&nbsp;come risolvere problemi legati a specifiche parti del corpo.<\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-laboratorio-asana-online\"><a href=\"https:\/\/eventiyoga.it\/blog\/prodotto\/laboratorio-asana-online\/\" class=\"ek-link\">Laboratorio Asana Online<\/a><\/h3>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/eventiyoga.it\/blog\/prodotto\/laboratorio-asana-online\/\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2021\/10\/LABORATORIO_ASANA-COVER-1.jpg\" alt=\"Laboratorio Asana Online\" class=\"wp-image-36205 size-full\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2021\/10\/LABORATORIO_ASANA-COVER-1.jpg\" alt=\"Laboratorio Asana Online\" class=\"wp-image-36205 size-full\"\/><\/noscript><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p>E\u2019 un laboratorio&nbsp;<strong>fondamentale per ogni praticante<\/strong>&nbsp;che voglia imparare ad eseguire gli asana nel modo corretto e in sicurezza.<\/p>\n\n\n\n<p>Il corso si svolge in modalit\u00e0 online, con spiegazioni semplici e video dimostrativi.<\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-hatha-yoga-online-con-insegnante-indiano\"><a href=\"https:\/\/eventiyoga.it\/blog\/prodotto\/corso-hatha-yoga-online\/\" class=\"ek-link\">Hatha Yoga Online con insegnante indiano<\/a><\/h3>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/eventiyoga.it\/blog\/prodotto\/corso-hatha-yoga-online\/\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2021\/10\/CORSO_HATA_YOGA_CON-INSEGNANTE_INDIANO_COVER.jpg\" alt=\"Corso Hatha Yoga Online\" class=\"wp-image-36546 size-full\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2021\/10\/CORSO_HATA_YOGA_CON-INSEGNANTE_INDIANO_COVER.jpg\" alt=\"Corso Hatha Yoga Online\" class=\"wp-image-36546 size-full\"\/><\/noscript><\/a><\/figure><div class=\"wp-block-media-text__content\">\n<p>Il <strong>Corso di Hatha Yoga<\/strong> per imparare gli asana pi\u00f9 importanti dello hatha yoga e scoprire come adattare la loro pratica al proprio corpo per trarre il maggior beneficio.<\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-tre-risorse-interessanti-per-te\"><span class=\"ez-toc-section\" id=\"Tre_risorse_interessanti_per_te\"><\/span>Tre risorse interessanti per te<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<p><strong><a href=\"https:\/\/eventiyoga.it\/blog\/benefici-gli-effetti-dello-yoga-nel-tempo\/\">I benefici e gli effetti dello yoga che durano nel tempo<\/a><\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/eventiyoga.it\/blog\/segreti-meditazione-senza-dolori\/\">I segreti per meditare senza dolori<\/a><\/strong><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/eventiyoga.it\/blog\/sale-caldo-a-che-serve-e-come-usarlo\/\">Sale caldo: come usarlo e tutti i benefici per alleviare i dolori<\/a><\/strong><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-iscriviti-alla-nostra-newsletter\"><span class=\"ez-toc-section\" id=\"Iscriviti_alla_nostra_newsletter\"><\/span>Iscriviti alla nostra newsletter<span class=\"ez-toc-section-end\"><\/span><\/h2>\n\n\n\n<figure class=\"wp-block-image caption-align-center\"><a href=\"https:\/\/eventiyoga.it\/blog\/newsletter-eventi-yoga\/\"><img decoding=\"async\" src=\"data:image\/gif;base64,R0lGODlhAQABAIAAAAAAAP\/\/\/yH5BAEAAAAALAAAAAABAAEAAAIBRAA7\" data-src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/10\/Banner-Iscrizione-NL.jpg\" alt=\"\" class=\"wp-image-16731\"\/><noscript><img decoding=\"async\" src=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2019\/10\/Banner-Iscrizione-NL.jpg\" alt=\"\" class=\"wp-image-16731\"\/><\/noscript><\/a><figcaption>Iscriviti alla Newsletter \u2013 Per te subito un Bonus!<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Come diceva il Maestro Pattabhi Jois, Yoga \u00e8 99% pratica ed 1% teoria. La pratica degli asana yoga \u00e8 la parte pi\u00f9 conosciuta dello Yoga e chi pratica sa che gli asana non sono solo esercizio fisico ma creano benessere nel corpo e nella mente cos\u00ec come una maggiore apertura mentale e spirituale accompagnando il [&hellip;]<\/p>\n","protected":false},"author":363,"featured_media":17885,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_editorskit_title_hidden":false,"_editorskit_reading_time":6,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","footnotes":""},"categories":[41],"tags":[38],"class_list":["post-6384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tips","tag-praticare-yoga"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Asana yoga: benefici e precauzioni da adottare nella pratica<\/title>\n<meta name=\"description\" content=\"Asana yoga: benefici e precauzioni da adottare nella pratica. Tutto quello che devi sapere sugli asana yoga per evitare problemi.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Asana yoga: benefici e precauzioni da adottare nella pratica\" \/>\n<meta property=\"og:description\" content=\"Asana yoga: benefici e precauzioni da adottare nella pratica. Tutto quello che devi sapere sugli asana yoga per evitare problemi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/\" \/>\n<meta property=\"og:site_name\" content=\"Eventi Yoga\" \/>\n<meta property=\"article:published_time\" content=\"2017-09-28T22:44:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-01T10:49:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2017\/09\/Asana-Yoga-Articolo-Blog.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/\",\"url\":\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/\",\"name\":\"Asana yoga: benefici e precauzioni da adottare nella pratica\",\"isPartOf\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2017\/09\/Asana-Yoga-Articolo-Blog.png\",\"datePublished\":\"2017-09-28T22:44:41+00:00\",\"dateModified\":\"2022-12-01T10:49:25+00:00\",\"author\":{\"@id\":\"\"},\"description\":\"Asana yoga: benefici e precauzioni da adottare nella pratica. Tutto quello che devi sapere sugli asana yoga per evitare problemi.\",\"breadcrumb\":{\"@id\":\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#primaryimage\",\"url\":\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2017\/09\/Asana-Yoga-Articolo-Blog.png\",\"contentUrl\":\"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2017\/09\/Asana-Yoga-Articolo-Blog.png\",\"width\":1024,\"height\":768},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/eventiyoga.it\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Asana yoga: benefici e precauzioni da adottare nella pratica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/eventiyoga.it\/blog\/#website\",\"url\":\"https:\/\/eventiyoga.it\/blog\/\",\"name\":\"Eventi Yoga\",\"description\":\"Il portale Italiano per gli eventi dello yoga\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/eventiyoga.it\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/eventiyoga.it\/blog\/author\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Asana yoga: benefici e precauzioni da adottare nella pratica","description":"Asana yoga: benefici e precauzioni da adottare nella pratica. Tutto quello che devi sapere sugli asana yoga per evitare problemi.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/","og_locale":"en_US","og_type":"article","og_title":"Asana yoga: benefici e precauzioni da adottare nella pratica","og_description":"Asana yoga: benefici e precauzioni da adottare nella pratica. Tutto quello che devi sapere sugli asana yoga per evitare problemi.","og_url":"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/","og_site_name":"Eventi Yoga","article_published_time":"2017-09-28T22:44:41+00:00","article_modified_time":"2022-12-01T10:49:25+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2017\/09\/Asana-Yoga-Articolo-Blog.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/","url":"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/","name":"Asana yoga: benefici e precauzioni da adottare nella pratica","isPartOf":{"@id":"https:\/\/eventiyoga.it\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#primaryimage"},"image":{"@id":"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#primaryimage"},"thumbnailUrl":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2017\/09\/Asana-Yoga-Articolo-Blog.png","datePublished":"2017-09-28T22:44:41+00:00","dateModified":"2022-12-01T10:49:25+00:00","author":{"@id":""},"description":"Asana yoga: benefici e precauzioni da adottare nella pratica. Tutto quello che devi sapere sugli asana yoga per evitare problemi.","breadcrumb":{"@id":"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#primaryimage","url":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2017\/09\/Asana-Yoga-Articolo-Blog.png","contentUrl":"https:\/\/eventiyoga.it\/blog\/wp-content\/uploads\/2017\/09\/Asana-Yoga-Articolo-Blog.png","width":1024,"height":768},{"@type":"BreadcrumbList","@id":"https:\/\/eventiyoga.it\/blog\/asana-yoga-benefici-e-precauzioni\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/eventiyoga.it\/blog\/"},{"@type":"ListItem","position":2,"name":"Asana yoga: benefici e precauzioni da adottare nella pratica"}]},{"@type":"WebSite","@id":"https:\/\/eventiyoga.it\/blog\/#website","url":"https:\/\/eventiyoga.it\/blog\/","name":"Eventi Yoga","description":"Il portale Italiano per gli eventi dello yoga","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/eventiyoga.it\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"","url":"https:\/\/eventiyoga.it\/blog\/author\/"}]}},"_links":{"self":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/posts\/6384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/users\/363"}],"replies":[{"embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/comments?post=6384"}],"version-history":[{"count":0,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/posts\/6384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/media\/17885"}],"wp:attachment":[{"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/media?parent=6384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/categories?post=6384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/eventiyoga.it\/blog\/wp-json\/wp\/v2\/tags?post=6384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}